{"id":139,"date":"2020-03-26T00:46:04","date_gmt":"2020-03-26T00:46:04","guid":{"rendered":"https:\/\/demosites.io\/rokophoto-gb\/?page_id=139"},"modified":"2022-07-28T14:22:23","modified_gmt":"2022-07-28T14:22:23","slug":"about-us-la-cruz-verde","status":"publish","type":"page","link":"https:\/\/lacruzverdebolivia.com\/es\/about-us-la-cruz-verde\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"<div id=\"wp-block-themeisle-blocks-advanced-columns-6fd49cfa\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-87827bcc\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h1 id=\"wp-block-themeisle-blocks-advanced-heading-93d7a316\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-93d7a316\"> Sobre Nosotros<\/h1>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-9ed733b5\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-2-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-collapsedRows-layout has-vertical-unset\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-e2e4f7ae\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h2 id=\"wp-block-themeisle-blocks-advanced-heading-8818cba9\" class=\"wp-block-themeisle-blocks-advanced-heading wp-block-themeisle-blocks-advanced-heading-8818cba9 animated fadeInLeft\">Sobre Nosotros<\/h2>\n\n\n\n<h3 class=\"animated fadeInLeft wp-block-heading\"><strong>LA CRUZ VERDE (THE GREEN CROSS)<\/strong><\/h3>\n\n\n\n<p class=\"animated fadeInLeft has-neve-text-color-color has-text-color\">La Cruz Verde es un proyecto comunitario sin fines de lucro que ofrece una experiencia \u00fanica en un lugar inspirador. El centro fue fundado en 2020 por el Sr. Fr\u00e9d\u00e9ric Bordier junto a la comunidad ind\u00edgena Carmen Florida. La Cruz Verde tiene como objetivo crear un centro de rehabilitaci\u00f3n para animales salvajes y cuidar el medio ambiente y la comunidad que lo rodea.<\/p>\n\n\n\n<p class=\"animated fadeInLeft has-neve-text-color-color has-text-color\"> <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-rounded animated fadeInLeft\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3.jpg?resize=458%2C305&#038;ssl=1\" alt=\"La Cruz Verde Wildlife\" class=\"wp-image-333\" width=\"458\" height=\"305\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=930%2C620&amp;ssl=1 930w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=174%2C116&amp;ssl=1 174w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 458px) 100vw, 458px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:69px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"animated fadeInLeft\">La idea principal detr\u00e1s del proyecto es crear un lugar inspirador, centr\u00e1ndose en la conservaci\u00f3n de la naturaleza y la salud y educaci\u00f3n de los miembros de la comunidad. Educar a la comunidad sobre pr\u00e1cticas sostenibles, respetando sus tradiciones y costumbres locales, puede ayudar a mantener el medio ambiente a largo plazo.&nbsp;<\/p>\n\n\n\n<p class=\"animated fadeInLeft has-neve-text-color-color has-text-color\"> <\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=800%2C600&#038;ssl=1\" alt=\"La Cruz Verde House\" class=\"wp-image-335\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=155%2C116&amp;ssl=1 155w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-column-9c1ad7b8\" class=\"wp-block-themeisle-blocks-advanced-column\"><div class=\"wp-block-image is-style-rounded animated fadeInRight\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/Logo-texte-FOND-BLANC-1.png?resize=321%2C321&#038;ssl=1\" alt=\"La Cruz Verde Logo\" class=\"wp-image-411\" width=\"321\" height=\"321\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/Logo-texte-FOND-BLANC-1.png?w=1017&amp;ssl=1 1017w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/Logo-texte-FOND-BLANC-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/Logo-texte-FOND-BLANC-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/Logo-texte-FOND-BLANC-1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/Logo-texte-FOND-BLANC-1.png?resize=116%2C116&amp;ssl=1 116w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Despu\u00e9s de 3 a\u00f1os de experiencia trabajando con animales salvajes y aprendiendo sobre las bellezas y carencias en las poblaciones de las comunidades ind\u00edgenas. Fr\u00e9d\u00e9ric decidi\u00f3 construir La Cruz Verde, junto con la Comunidad Carmen Florida. En un trato hist\u00f3rico, Fr\u00e9d\u00e9ric fue recibido como miembro de la comunidad y tom\u00f3 prestado el terreno para el centro. Como primer paso, se han fijado unos objetivos y est\u00e1 en marcha la creaci\u00f3n del centro.\u00a0<\/p>\n\n\n\n<div style=\"height:76px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded animated fadeInRight\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A6117-1.jpg?w=1200&#038;ssl=1\" alt=\"La Cruz Verde Animal\" class=\"wp-image-327\"\/><\/figure>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Adem\u00e1s, se ha creado un fondo de salud a trav\u00e9s de las contribuciones de los voluntarios. Este fondo es accesible a los miembros de la comunidad en casos de emergencias, accidentes y enfermedades. Se ofrecer\u00e1n cursos de educaci\u00f3n y capacitaci\u00f3n como Tacana, Ingl\u00e9s, Matem\u00e1ticas y Educaci\u00f3n Ambiental. Estas clases ser\u00e1n impartidas por maestros y voluntarios locales.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter is-style-rectangular\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-328\" data-id=\"328\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7479.jpg?w=1200&#038;ssl=1\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" alt=\"La Cruz Verde Animal\" class=\"wp-block-jetpack-slideshow_image wp-image-333\" data-id=\"333\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=1200%2C800&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=930%2C620&amp;ssl=1 930w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?resize=174%2C116&amp;ssl=1 174w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" alt=\"La Cruz Verde House\" class=\"wp-block-jetpack-slideshow_image wp-image-335\" data-id=\"335\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=800%2C600&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/HOUSE.jpeg?resize=155%2C116&amp;ssl=1 155w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"La Cruz Verde Animal\" class=\"wp-block-jetpack-slideshow_image wp-image-327\" data-id=\"327\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A6117-1.jpg?w=1200&#038;ssl=1\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" alt=\"La Cruz Verde Animal\" class=\"wp-block-jetpack-slideshow_image wp-image-322\" data-id=\"322\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?resize=1200%2C1200&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/def39706-7c19-4a8c-8447-ead4835e6faf-copy-1.jpg?resize=116%2C116&amp;ssl=1 116w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-292\" data-id=\"292\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A4969-2-1.jpg?w=1200&#038;ssl=1\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-323\" data-id=\"323\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/ab947be1-8861-4017-977d-fab4504f7e43.jpg?resize=960%2C1280&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/ab947be1-8861-4017-977d-fab4504f7e43.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/ab947be1-8861-4017-977d-fab4504f7e43.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/ab947be1-8861-4017-977d-fab4504f7e43.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/ab947be1-8861-4017-977d-fab4504f7e43.jpg?resize=87%2C116&amp;ssl=1 87w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" alt=\"La Cruz Verde Animal\" class=\"wp-block-jetpack-slideshow_image wp-image-285\" data-id=\"285\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=1200%2C800&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=930%2C620&amp;ssl=1 930w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?resize=174%2C116&amp;ssl=1 174w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A2968-3-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" alt=\"La Cruz Verde Animal\" class=\"wp-block-jetpack-slideshow_image wp-image-278\" data-id=\"278\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?resize=1200%2C800&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3020-2-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-274\" data-id=\"274\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/be7dee52-ed94-4be5-b89a-97db43960101-2.jpg?resize=1200%2C900&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/be7dee52-ed94-4be5-b89a-97db43960101-2.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/be7dee52-ed94-4be5-b89a-97db43960101-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/be7dee52-ed94-4be5-b89a-97db43960101-2.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/be7dee52-ed94-4be5-b89a-97db43960101-2.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/be7dee52-ed94-4be5-b89a-97db43960101-2.jpg?resize=155%2C116&amp;ssl=1 155w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"793\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-252\" data-id=\"252\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=1200%2C793&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=1024%2C676&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=768%2C507&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=1536%2C1014&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=2048%2C1353&amp;ssl=1 2048w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?resize=176%2C116&amp;ssl=1 176w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5356-1-2-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"La Cruz Verde Animal\" class=\"wp-block-jetpack-slideshow_image wp-image-253\" data-id=\"253\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A5361.jpg?w=1200&#038;ssl=1\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-238\" data-id=\"238\" src=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?resize=1200%2C800&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A7249-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"neve_meta_sidebar":"full-width","neve_meta_container":"contained","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-139","page","type-page","status-publish","hentry"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Us La Cruz Verde<\/title>\n<meta name=\"description\" content=\"Find out about La Cruz Verde. A world first wildlife rehabilitation center working with the community of Carmen Florida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacruzverdebolivia.com\/es\/about-us-la-cruz-verde\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us La Cruz Verde\" \/>\n<meta property=\"og:description\" content=\"Find out about La Cruz Verde. A world first wildlife rehabilitation center working with the community of Carmen Florida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacruzverdebolivia.com\/es\/about-us-la-cruz-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cruz Verde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Cruz-Verde-109375797562296\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-28T14:22:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/\",\"url\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/\",\"name\":\"About Us La Cruz Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/261A3286-3-3-1024x683.jpg\",\"datePublished\":\"2020-03-26T00:46:04+00:00\",\"dateModified\":\"2022-07-28T14:22:23+00:00\",\"description\":\"Find out about La Cruz Verde. A world first wildlife rehabilitation center working with the community of Carmen Florida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/261A3286-3-3-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/261A3286-3-3-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/about-us-la-cruz-verde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/#website\",\"url\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/\",\"name\":\"La Cruz Verde\",\"description\":\"Wildlife rehabilitation center, working with the indigenous community of Carmen Florida, to protect and reintegrate the wildlife of the Bolivian Amazon\",\"publisher\":{\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/#organization\",\"name\":\"La Cruz Verde\",\"url\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/LOGO-COMPLET-CRUZ-VERDE-SVG-1.svg\",\"contentUrl\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/LOGO-COMPLET-CRUZ-VERDE-SVG-1.svg\",\"width\":1,\"height\":1,\"caption\":\"La Cruz Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/lacruzverdebolivia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Cruz-Verde-109375797562296\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Us La Cruz Verde","description":"Find out about La Cruz Verde. A world first wildlife rehabilitation center working with the community of Carmen Florida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacruzverdebolivia.com\/es\/about-us-la-cruz-verde\/","og_locale":"es_ES","og_type":"article","og_title":"About Us La Cruz Verde","og_description":"Find out about La Cruz Verde. A world first wildlife rehabilitation center working with the community of Carmen Florida.","og_url":"https:\/\/lacruzverdebolivia.com\/es\/about-us-la-cruz-verde\/","og_site_name":"La Cruz Verde","article_publisher":"https:\/\/www.facebook.com\/La-Cruz-Verde-109375797562296\/","article_modified_time":"2022-07-28T14:22:23+00:00","og_image":[{"url":"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/","url":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/","name":"About Us La Cruz Verde","isPartOf":{"@id":"https:\/\/lacruzverdebolivia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/#primaryimage"},"image":{"@id":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-1024x683.jpg","datePublished":"2020-03-26T00:46:04+00:00","dateModified":"2022-07-28T14:22:23+00:00","description":"Find out about La Cruz Verde. A world first wildlife rehabilitation center working with the community of Carmen Florida.","breadcrumb":{"@id":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/#primaryimage","url":"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-1024x683.jpg","contentUrl":"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/261A3286-3-3-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lacruzverdebolivia.com\/about-us-la-cruz-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lacruzverdebolivia.com\/"},{"@type":"ListItem","position":2,"name":"About Us"}]},{"@type":"WebSite","@id":"https:\/\/lacruzverdebolivia.com\/#website","url":"https:\/\/lacruzverdebolivia.com\/","name":"La Cruz Verde","description":"Wildlife rehabilitation center, working with the indigenous community of Carmen Florida, to protect and reintegrate the wildlife of the Bolivian Amazon","publisher":{"@id":"https:\/\/lacruzverdebolivia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacruzverdebolivia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lacruzverdebolivia.com\/#organization","name":"La Cruz Verde","url":"https:\/\/lacruzverdebolivia.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lacruzverdebolivia.com\/#\/schema\/logo\/image\/","url":"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/LOGO-COMPLET-CRUZ-VERDE-SVG-1.svg","contentUrl":"https:\/\/lacruzverdebolivia.com\/wp-content\/uploads\/2022\/06\/LOGO-COMPLET-CRUZ-VERDE-SVG-1.svg","width":1,"height":1,"caption":"La Cruz Verde"},"image":{"@id":"https:\/\/lacruzverdebolivia.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Cruz-Verde-109375797562296\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/pages\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":5,"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/pages\/139\/revisions"}],"predecessor-version":[{"id":481,"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/pages\/139\/revisions\/481"}],"wp:attachment":[{"href":"https:\/\/lacruzverdebolivia.com\/es\/wp-json\/wp\/v2\/media?parent=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}